{"id":9037,"date":"2017-10-05T19:34:41","date_gmt":"2017-10-05T19:34:41","guid":{"rendered":"http:\/\/delucine.com\/un-autre-monde\/?p=9037"},"modified":"2022-04-08T19:55:26","modified_gmt":"2022-04-08T19:55:26","slug":"2-premiers-tomes-du-gon","status":"publish","type":"post","link":"https:\/\/delucine.com\/un-autre-monde\/2-premiers-tomes-du-gon\/","title":{"rendered":"Les 2 premiers tomes du GON"},"content":{"rendered":"<p>Quelques photos qui ont \u00e9t\u00e9 s\u00e9lectionn\u00e9es dans ces 2 ouvrages (Machaon, Carte g\u00e9ographique, Robert le diable&#8230; )&#8230; A suivre\u00a0<span class=\"_47e3 _5mfr\" title=\"\u00e9motic\u00f4ne wink\"><img decoding=\"async\" class=\"img\" role=\"presentation\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/f57\/1\/16\/1f609.png\" alt=\"\" width=\"16\" height=\"16\" \/><\/span><\/p>\n<p><strong>Le Groupe ornithologique et naturaliste du Nord &#8211; Pas-de-Calais (GON) pr\u00e9sente sa nouvelle marque \u00e9ditoriale \u00ab\u00a0Faune du Nord \u2013 Pas-de\u00ad-Calais\u00a0\u00bb et les deux premiers tomes de la s\u00e9rie\u00a0:<\/strong><\/p>\n<p>[ezcol_1third]<img data-recalc-dims=\"1\" decoding=\"async\" width=\"138\" height=\"188\" class=\"alignleft size-full wp-image-9039\" src=\"https:\/\/i0.wp.com\/delucine.com\/un-autre-monde\/wp-content\/uploads\/2017\/10\/gon-tome-1.png?resize=138%2C188\" alt=\"\" \/>[\/ezcol_1third] [ezcol_2third_end]<strong>Le tome 1, consacr\u00e9 aux oiseaux<\/strong>, dresse un \u00e9tat des populations d\u2019oiseaux communs (Merle noir, Moineau domestique, M\u00e9sange charbonni\u00e8re, etc.) dans le Nord &#8211; Pas-de-Calais et vient donner des \u00e9l\u00e9ments chiffr\u00e9s permettant de conforter certains ressentis de terrain (ex.\u00a0: de nombreuses esp\u00e8ces des milieux agricoles, telles l\u2019Alouette des champs, la Tourterelle des bois ou la Linotte m\u00e9lodieuse pr\u00e9sentent des baisses d\u2019effectifs tr\u00e8s importantes\u00a0; le Moineau domestique est effectivement en d\u00e9clin, mais aussi l\u2019\u00c9tourneau sansonnet, etc.).[\/ezcol_2third_end]<\/p>\n<p>[ezcol_1third]<img data-recalc-dims=\"1\" decoding=\"async\" width=\"136\" height=\"188\" class=\"alignleft size-full wp-image-9040\" src=\"https:\/\/i0.wp.com\/delucine.com\/un-autre-monde\/wp-content\/uploads\/2017\/10\/gon-tome-2.png?resize=136%2C188\" alt=\"\" \/>[\/ezcol_1third] [ezcol_2third_end]<strong>Le tome 2, consacr\u00e9 aux papillons<\/strong>, propose un bilan in\u00e9gal\u00e9 \u00e0 ce jour sur la connaissance relative \u00e0 ces insectes dans le Nord &#8211; Pas-de-Calais. Cartes de r\u00e9partition, graphiques ph\u00e9nologiques, informations in\u00e9dites sur la biologie et les comportements de certaines esp\u00e8ces dans notre r\u00e9gion, Liste rouge et \u00e9tat de conservation pour chacune des esp\u00e8ces\u2026 Cet ouvrage de pr\u00e8s de 500 pages, d\u2019une incroyable qualit\u00e9 iconographique, ravira tr\u00e8s certainement ses lecteurs \u00e0 la fois par la pr\u00e9cision de son contenu et par son accessibilit\u00e9.[\/ezcol_2third_end]<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quelques photos qui ont \u00e9t\u00e9 s\u00e9lectionn\u00e9es dans ces 2 ouvrages (Machaon, Carte g\u00e9ographique, Robert le diable&#8230; )&#8230; A suivre\u00a0 Le Groupe ornithologique et naturaliste du Nord &#8211; Pas-de-Calais (GON) pr\u00e9sente sa nouvelle marque \u00e9ditoriale \u00ab\u00a0Faune du Nord \u2013 Pas-de\u00ad-Calais\u00a0\u00bb et les deux premiers tomes de la s\u00e9rie\u00a0: [ezcol_1third][\/ezcol_1third] [ezcol_2third_end]Le tome 1, consacr\u00e9 aux oiseaux, dresse [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9038,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[451,8],"tags":[],"class_list":["post-9037","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-publications","category-sur-nos-chemins","post_format-post-format-image"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/delucine.com\/un-autre-monde\/wp-content\/uploads\/2017\/10\/7c679d566900de2b77e943f6abc4df.png?fit=450%2C250&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/delucine.com\/un-autre-monde\/wp-json\/wp\/v2\/posts\/9037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delucine.com\/un-autre-monde\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/delucine.com\/un-autre-monde\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/delucine.com\/un-autre-monde\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/delucine.com\/un-autre-monde\/wp-json\/wp\/v2\/comments?post=9037"}],"version-history":[{"count":1,"href":"https:\/\/delucine.com\/un-autre-monde\/wp-json\/wp\/v2\/posts\/9037\/revisions"}],"predecessor-version":[{"id":9041,"href":"https:\/\/delucine.com\/un-autre-monde\/wp-json\/wp\/v2\/posts\/9037\/revisions\/9041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/delucine.com\/un-autre-monde\/wp-json\/wp\/v2\/media\/9038"}],"wp:attachment":[{"href":"https:\/\/delucine.com\/un-autre-monde\/wp-json\/wp\/v2\/media?parent=9037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/delucine.com\/un-autre-monde\/wp-json\/wp\/v2\/categories?post=9037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/delucine.com\/un-autre-monde\/wp-json\/wp\/v2\/tags?post=9037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}